{"id":10756,"date":"2021-07-25T11:54:28","date_gmt":"2021-07-25T09:54:28","guid":{"rendered":"https:\/\/vinosomodena.it\/?post_type=product&#038;p=10756"},"modified":"2026-01-28T16:18:02","modified_gmt":"2026-01-28T15:18:02","slug":"paolo-scavino-barolo-bric-del-fiasc-1988","status":"publish","type":"product","link":"https:\/\/vinosomodena.it\/en\/prodotto\/paolo-scavino-barolo-bric-del-fiasc-1988\/","title":{"rendered":"Paolo Scavino Barolo Bric del Fiasc 1988"},"content":{"rendered":"<p>Il \u201cBric del Fiasc\u201d \u00e8 il Barolo della cantina Paolo Scavino, un\u2019esplosione liquida di spezie, sottobosco e liquirizia, figlio legittimo della terra da cui proviene. La storia prestigiosa di questa etichetta si lega alla lungimiranza di Enrico, che nel 1978 convinse il padre Paolo a vinificare singolarmente le uve Nebbiolo provenienti dal vigneto Fiasco, di antica propriet\u00e0 della famiglia, nel cuore della collina di Castiglione Falletto. Un rosso di potenza e struttura che parla piemontese e narra una delle pi\u00f9 storiche e rinomate realt\u00e0 vitivinicole del Barolo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il \u201cBric del Fiasc\u201d \u00e8 il Barolo della cantina Paolo Scavino, un\u2019esplosione liquida di spezie, sottobosco e liquirizia, figlio legittimo della terra da cui proviene. La storia prestigiosa di questa etichetta si lega alla lungimiranza di Enrico, che nel 1978 convinse il padre Paolo a vinificare singolarmente le uve Nebbiolo provenienti dal vigneto Fiasco, di antica propriet\u00e0 della famiglia, nel cuore della collina di Castiglione Falletto. Un rosso di potenza e struttura che parla piemontese e narra una delle pi\u00f9 storiche e rinomate realt\u00e0 vitivinicole del Barolo<\/p>\n","protected":false},"featured_media":28655,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2579],"product_tag":[],"class_list":["post-10756","product","type-product","status-publish","has-post-thumbnail","product_cat-red-wine","first","instock","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paolo Scavino Barolo Bric del Fiasc 1988 - Vinoso Modena<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vinosomodena.it\/prodotto\/paolo-scavino-barolo-bric-del-fiasc-1988\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paolo Scavino Barolo Bric del Fiasc 1988 - Vinoso Modena\" \/>\n<meta property=\"og:description\" content=\"Il \u201cBric del Fiasc\u201d \u00e8 il Barolo della cantina Paolo Scavino, un\u2019esplosione liquida di spezie, sottobosco e liquirizia, figlio legittimo della terra da cui proviene. La storia prestigiosa di questa etichetta si lega alla lungimiranza di Enrico, che nel 1978 convinse il padre Paolo a vinificare singolarmente le uve Nebbiolo provenienti dal vigneto Fiasco, di antica propriet\u00e0 della famiglia, nel cuore della collina di Castiglione Falletto. Un rosso di potenza e struttura che parla piemontese e narra una delle pi\u00f9 storiche e rinomate realt\u00e0 vitivinicole del Barolo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vinosomodena.it\/prodotto\/paolo-scavino-barolo-bric-del-fiasc-1988\/\" \/>\n<meta property=\"og:site_name\" content=\"Vinoso Modena\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T15:18:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vinosomodena.it\/wp-content\/uploads\/2026\/07\/1697211741_Paolo20Scavino20Barolo20Bric20del20Fiasc201988-\u2014.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1923\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vinosomodena.it\\\/prodotto\\\/paolo-scavino-barolo-bric-del-fiasc-1988\\\/\",\"url\":\"https:\\\/\\\/vinosomodena.it\\\/prodotto\\\/paolo-scavino-barolo-bric-del-fiasc-1988\\\/\",\"name\":\"Paolo Scavino Barolo Bric del Fiasc 1988 - Vinoso Modena\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vinosomodena.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vinosomodena.it\\\/prodotto\\\/paolo-scavino-barolo-bric-del-fiasc-1988\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vinosomodena.it\\\/prodotto\\\/paolo-scavino-barolo-bric-del-fiasc-1988\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vinosomodena.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/1697211741_Paolo20Scavino20Barolo20Bric20del20Fiasc201988-\u2014.jpg\",\"datePublished\":\"2021-07-25T09:54:28+00:00\",\"dateModified\":\"2026-01-28T15:18:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vinosomodena.it\\\/prodotto\\\/paolo-scavino-barolo-bric-del-fiasc-1988\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vinosomodena.it\\\/prodotto\\\/paolo-scavino-barolo-bric-del-fiasc-1988\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/vinosomodena.it\\\/prodotto\\\/paolo-scavino-barolo-bric-del-fiasc-1988\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vinosomodena.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/1697211741_Paolo20Scavino20Barolo20Bric20del20Fiasc201988-\u2014.jpg\",\"contentUrl\":\"https:\\\/\\\/vinosomodena.it\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/1697211741_Paolo20Scavino20Barolo20Bric20del20Fiasc201988-\u2014.jpg\",\"width\":1500,\"height\":1923},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vinosomodena.it\\\/prodotto\\\/paolo-scavino-barolo-bric-del-fiasc-1988\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vinosomodena.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/vinosomodena.it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Paolo Scavino Barolo Bric del Fiasc 1988\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vinosomodena.it\\\/#website\",\"url\":\"https:\\\/\\\/vinosomodena.it\\\/\",\"name\":\"Vinoso Modena\",\"description\":\"I migliori vini, le annate storiche e molto altro ancora.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vinosomodena.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paolo Scavino Barolo Bric del Fiasc 1988 - Vinoso Modena","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vinosomodena.it\/prodotto\/paolo-scavino-barolo-bric-del-fiasc-1988\/","og_locale":"en_US","og_type":"article","og_title":"Paolo Scavino Barolo Bric del Fiasc 1988 - Vinoso Modena","og_description":"Il \u201cBric del Fiasc\u201d \u00e8 il Barolo della cantina Paolo Scavino, un\u2019esplosione liquida di spezie, sottobosco e liquirizia, figlio legittimo della terra da cui proviene. La storia prestigiosa di questa etichetta si lega alla lungimiranza di Enrico, che nel 1978 convinse il padre Paolo a vinificare singolarmente le uve Nebbiolo provenienti dal vigneto Fiasco, di antica propriet\u00e0 della famiglia, nel cuore della collina di Castiglione Falletto. Un rosso di potenza e struttura che parla piemontese e narra una delle pi\u00f9 storiche e rinomate realt\u00e0 vitivinicole del Barolo","og_url":"https:\/\/vinosomodena.it\/prodotto\/paolo-scavino-barolo-bric-del-fiasc-1988\/","og_site_name":"Vinoso Modena","article_modified_time":"2026-01-28T15:18:02+00:00","og_image":[{"width":1500,"height":1923,"url":"https:\/\/vinosomodena.it\/wp-content\/uploads\/2026\/07\/1697211741_Paolo20Scavino20Barolo20Bric20del20Fiasc201988-\u2014.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vinosomodena.it\/prodotto\/paolo-scavino-barolo-bric-del-fiasc-1988\/","url":"https:\/\/vinosomodena.it\/prodotto\/paolo-scavino-barolo-bric-del-fiasc-1988\/","name":"Paolo Scavino Barolo Bric del Fiasc 1988 - Vinoso Modena","isPartOf":{"@id":"https:\/\/vinosomodena.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vinosomodena.it\/prodotto\/paolo-scavino-barolo-bric-del-fiasc-1988\/#primaryimage"},"image":{"@id":"https:\/\/vinosomodena.it\/prodotto\/paolo-scavino-barolo-bric-del-fiasc-1988\/#primaryimage"},"thumbnailUrl":"https:\/\/vinosomodena.it\/wp-content\/uploads\/2026\/07\/1697211741_Paolo20Scavino20Barolo20Bric20del20Fiasc201988-\u2014.jpg","datePublished":"2021-07-25T09:54:28+00:00","dateModified":"2026-01-28T15:18:02+00:00","breadcrumb":{"@id":"https:\/\/vinosomodena.it\/prodotto\/paolo-scavino-barolo-bric-del-fiasc-1988\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vinosomodena.it\/prodotto\/paolo-scavino-barolo-bric-del-fiasc-1988\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vinosomodena.it\/prodotto\/paolo-scavino-barolo-bric-del-fiasc-1988\/#primaryimage","url":"https:\/\/vinosomodena.it\/wp-content\/uploads\/2026\/07\/1697211741_Paolo20Scavino20Barolo20Bric20del20Fiasc201988-\u2014.jpg","contentUrl":"https:\/\/vinosomodena.it\/wp-content\/uploads\/2026\/07\/1697211741_Paolo20Scavino20Barolo20Bric20del20Fiasc201988-\u2014.jpg","width":1500,"height":1923},{"@type":"BreadcrumbList","@id":"https:\/\/vinosomodena.it\/prodotto\/paolo-scavino-barolo-bric-del-fiasc-1988\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vinosomodena.it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/vinosomodena.it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Paolo Scavino Barolo Bric del Fiasc 1988"}]},{"@type":"WebSite","@id":"https:\/\/vinosomodena.it\/#website","url":"https:\/\/vinosomodena.it\/","name":"Vinoso Modena","description":"I migliori vini, le annate storiche e molto altro ancora.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vinosomodena.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/vinosomodena.it\/en\/wp-json\/wp\/v2\/product\/10756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinosomodena.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vinosomodena.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinosomodena.it\/en\/wp-json\/wp\/v2\/media\/28655"}],"wp:attachment":[{"href":"https:\/\/vinosomodena.it\/en\/wp-json\/wp\/v2\/media?parent=10756"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vinosomodena.it\/en\/wp-json\/wp\/v2\/product_brand?post=10756"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vinosomodena.it\/en\/wp-json\/wp\/v2\/product_cat?post=10756"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vinosomodena.it\/en\/wp-json\/wp\/v2\/product_tag?post=10756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}